{"id":4792,"date":"2026-03-10T12:32:15","date_gmt":"2026-03-10T12:32:15","guid":{"rendered":"https:\/\/riberasalud.com\/rsc\/?p=4792"},"modified":"2026-03-10T12:32:17","modified_gmt":"2026-03-10T12:32:17","slug":"el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves","status":"publish","type":"post","link":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/","title":{"rendered":"El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>M\u00e1s de medio centenar de vecinos participan en un taller pr\u00e1ctico impartido en ingl\u00e9s para mejorar la respuesta ante emergencias sanitarias<\/strong><\/li>\n<\/ul>\n\n\n\n<p>El Departamento de Salud del Vinalop\u00f3, del grupo sanitario Ribera, en colaboraci\u00f3n con el Ayuntamiento de Hond\u00f3n de las Nieves, ha organizado un taller de Reanimaci\u00f3n Cardiopulmonar (RCP) y primeros auxilios dirigido a la poblaci\u00f3n extranjera del municipio.<\/p>\n\n\n\n<p>El taller ha sido impartido \u00edntegramente en ingl\u00e9s por Juan Miguel Alarc\u00f3n y Marien Beras, m\u00e9dicos residentes de Medicina Familiar y Comunitaria, supervisados por los doctores Daniel Buend\u00eda y Mar\u00eda Mart\u00ednez, quienes han ofrecido una formaci\u00f3n eminentemente pr\u00e1ctica y din\u00e1mica. Gracias al enfoque participativo se ha adaptado el taller a las necesidades reales de los vecinos, reforzando el compromiso del hospital con una atenci\u00f3n sanitaria cercana, inclusiva y orientada a la comunidad. A lo largo de la sesi\u00f3n, los asistentes han adquirido conocimientos clave para identificar situaciones de emergencia y actuar de forma r\u00e1pida y eficaz hasta la llegada de los servicios sanitarios.<\/p>\n\n\n\n<p>Un total de 50 personas han participado activamente en el taller, combinando contenidos te\u00f3ricos con la pr\u00e1ctica de maniobras de RCP, lo que les ha permitido afianzar habilidades fundamentales que pueden resultar decisivas para salvar vidas.<\/p>\n\n\n\n<p>\u201cNuestro objetivo es que cada persona se sienta preparada para actuar en una situaci\u00f3n de emergencia. Saber realizar correctamente la RCP o primeros auxilios puede marcar la diferencia entre la vida y la muerte, y por eso es fundamental acercar estos conocimientos a toda la comunidad\u201d, explic\u00f3 Juan Miguel Alarc\u00f3n, m\u00e9dico residente de Medicina Familiar y Comunitaria.<\/p>\n\n\n\n<p>La actividad ha sido muy bien valorada por los asistentes y pone de relieve la importancia de desarrollar intervenciones comunitarias adaptadas a la diversidad cultural y ling\u00fc\u00edstica de la poblaci\u00f3n. Desde el Departamento de Salud del Vinalop\u00f3 se contin\u00faa apostando por este tipo de acciones de promoci\u00f3n de la salud, que fomentan la prevenci\u00f3n, la capacitaci\u00f3n ciudadana y la cohesi\u00f3n social.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento de Salud del Vinalop\u00f3, del grupo sanitario Ribera, en colaboraci\u00f3n con el Ayuntamiento de Hond\u00f3n de las Nieves, ha organizado un taller de Reanimaci\u00f3n Cardiopulmonar (RCP) y primeros auxilios dirigido a la poblaci\u00f3n extranjera del municipio. El taller ha sido impartido \u00edntegramente en ingl\u00e9s por Juan Miguel Alarc\u00f3n y Marien Beras, m\u00e9dicos residentes &#8230; <a title=\"El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves\" class=\"read-more\" href=\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/\" aria-label=\"Leer m\u00e1s sobre El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":4793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_uag_custom_page_level_css":"","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[207,203,204],"tags":[831,133,12,53],"class_list":["post-4792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alianzas-con-el-entorno","category-educacion-para-la-salud","category-promocion-de-la-salud","tag-extranjeros","tag-primeros-auxilios","tag-rcp","tag-taller"],"featured_image_urls_v2":{"full":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"thumbnail":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2-150x150.jpeg",150,150,true],"medium":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2-300x200.jpeg",300,200,true],"medium_large":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2-768x512.jpeg",768,512,true],"large":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xxl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xxxl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xxxxl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xxxxxl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"1536x1536":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"2048x2048":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false]},"post_excerpt_stackable_v2":"<p>M\u00e1s de medio centenar de vecinos participan en un taller pr\u00e1ctico impartido en ingl\u00e9s para mejorar la respuesta ante emergencias sanitarias El Departamento de Salud del Vinalop\u00f3, del grupo sanitario Ribera, en colaboraci\u00f3n con el Ayuntamiento de Hond\u00f3n de las Nieves, ha organizado un taller de Reanimaci\u00f3n Cardiopulmonar (RCP) y primeros auxilios dirigido a la poblaci\u00f3n extranjera del municipio. El taller ha sido impartido \u00edntegramente en ingl\u00e9s por Juan Miguel Alarc\u00f3n y Marien Beras, m\u00e9dicos residentes de Medicina Familiar y Comunitaria, supervisados por los doctores Daniel Buend\u00eda y Mar\u00eda Mart\u00ednez, quienes han ofrecido una formaci\u00f3n eminentemente pr\u00e1ctica y din\u00e1mica. Gracias&hellip;<\/p>\n","category_list_v2":"<a href=\"https:\/\/riberasalud.com\/rsc\/category\/alianzas-con-el-entorno\/\" rel=\"category tag\">Alianzas con el entorno<\/a>, <a href=\"https:\/\/riberasalud.com\/rsc\/category\/educacion-para-la-salud\/\" rel=\"category tag\">Educaci\u00f3n para la salud<\/a>, <a href=\"https:\/\/riberasalud.com\/rsc\/category\/promocion-de-la-salud\/\" rel=\"category tag\">Promoci\u00f3n de la salud<\/a>","author_info_v2":{"name":"Mar Sanchez","url":"https:\/\/riberasalud.com\/rsc\/author\/msotoriberasalud-es\/"},"comments_num_v2":"0 comentarios","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves - RSC Grupo sanitario Ribera<\/title>\n<meta name=\"description\" content=\"M\u00e1s de medio centenar de vecinos participan en un taller pr\u00e1ctico impartido en ingl\u00e9s para mejorar la respuesta ante emergencias sanitarias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves - RSC Grupo sanitario Ribera\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s de medio centenar de vecinos participan en un taller pr\u00e1ctico impartido en ingl\u00e9s para mejorar la respuesta ante emergencias sanitarias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/\" \/>\n<meta property=\"og:site_name\" content=\"RSC Grupo sanitario Ribera\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-10T12:32:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T12:32:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mar Sanchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mar Sanchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/\"},\"author\":{\"name\":\"Mar Sanchez\",\"@id\":\"https:\/\/riberasalud.com\/rsc\/#\/schema\/person\/11c4e77d56d084661ced188afcae969f\"},\"headline\":\"El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves\",\"datePublished\":\"2026-03-10T12:32:15+00:00\",\"dateModified\":\"2026-03-10T12:32:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/\"},\"wordCount\":367,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/riberasalud.com\/rsc\/#organization\"},\"image\":{\"@id\":\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg\",\"keywords\":[\"extranjeros\",\"primeros auxilios\",\"rcp\",\"taller\"],\"articleSection\":[\"Alianzas con el entorno\",\"Educaci\u00f3n para la salud\",\"Promoci\u00f3n de la salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/\",\"url\":\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/\",\"name\":\"El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves - RSC Grupo sanitario Ribera\",\"isPartOf\":{\"@id\":\"https:\/\/riberasalud.com\/rsc\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg\",\"datePublished\":\"2026-03-10T12:32:15+00:00\",\"dateModified\":\"2026-03-10T12:32:17+00:00\",\"description\":\"M\u00e1s de medio centenar de vecinos participan en un taller pr\u00e1ctico impartido en ingl\u00e9s para mejorar la respuesta ante emergencias sanitarias\",\"breadcrumb\":{\"@id\":\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#primaryimage\",\"url\":\"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg\",\"contentUrl\":\"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg\",\"width\":800,\"height\":533,\"caption\":\"Taller RCP para poblaci\u00f3n extranjera\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/riberasalud.com\/rsc\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/riberasalud.com\/rsc\/#website\",\"url\":\"https:\/\/riberasalud.com\/rsc\/\",\"name\":\"RSC Grupo sanitario Ribera\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/riberasalud.com\/rsc\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/riberasalud.com\/rsc\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/riberasalud.com\/rsc\/#organization\",\"name\":\"RSC Grupo sanitario Ribera\",\"url\":\"https:\/\/riberasalud.com\/rsc\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/riberasalud.com\/rsc\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2021\/05\/cropped-Logotipo-Red.png\",\"contentUrl\":\"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2021\/05\/cropped-Logotipo-Red.png\",\"width\":500,\"height\":198,\"caption\":\"RSC Grupo sanitario Ribera\"},\"image\":{\"@id\":\"https:\/\/riberasalud.com\/rsc\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/riberasalud.com\/rsc\/#\/schema\/person\/11c4e77d56d084661ced188afcae969f\",\"name\":\"Mar Sanchez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/riberasalud.com\/rsc\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5fc005413aafe0a1f7d81747fac73740246ee36e4fad7f56eb325711b6c9f209?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5fc005413aafe0a1f7d81747fac73740246ee36e4fad7f56eb325711b6c9f209?s=96&d=mm&r=g\",\"caption\":\"Mar Sanchez\"},\"url\":\"https:\/\/riberasalud.com\/rsc\/author\/msotoriberasalud-es\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves - RSC Grupo sanitario Ribera","description":"M\u00e1s de medio centenar de vecinos participan en un taller pr\u00e1ctico impartido en ingl\u00e9s para mejorar la respuesta ante emergencias sanitarias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/","og_locale":"es_ES","og_type":"article","og_title":"El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves - RSC Grupo sanitario Ribera","og_description":"M\u00e1s de medio centenar de vecinos participan en un taller pr\u00e1ctico impartido en ingl\u00e9s para mejorar la respuesta ante emergencias sanitarias","og_url":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/","og_site_name":"RSC Grupo sanitario Ribera","article_published_time":"2026-03-10T12:32:15+00:00","article_modified_time":"2026-03-10T12:32:17+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg","type":"image\/jpeg"}],"author":"Mar Sanchez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Mar Sanchez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#article","isPartOf":{"@id":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/"},"author":{"name":"Mar Sanchez","@id":"https:\/\/riberasalud.com\/rsc\/#\/schema\/person\/11c4e77d56d084661ced188afcae969f"},"headline":"El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves","datePublished":"2026-03-10T12:32:15+00:00","dateModified":"2026-03-10T12:32:17+00:00","mainEntityOfPage":{"@id":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/"},"wordCount":367,"commentCount":0,"publisher":{"@id":"https:\/\/riberasalud.com\/rsc\/#organization"},"image":{"@id":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#primaryimage"},"thumbnailUrl":"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg","keywords":["extranjeros","primeros auxilios","rcp","taller"],"articleSection":["Alianzas con el entorno","Educaci\u00f3n para la salud","Promoci\u00f3n de la salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/","url":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/","name":"El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves - RSC Grupo sanitario Ribera","isPartOf":{"@id":"https:\/\/riberasalud.com\/rsc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#primaryimage"},"image":{"@id":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#primaryimage"},"thumbnailUrl":"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg","datePublished":"2026-03-10T12:32:15+00:00","dateModified":"2026-03-10T12:32:17+00:00","description":"M\u00e1s de medio centenar de vecinos participan en un taller pr\u00e1ctico impartido en ingl\u00e9s para mejorar la respuesta ante emergencias sanitarias","breadcrumb":{"@id":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#primaryimage","url":"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg","contentUrl":"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg","width":800,"height":533,"caption":"Taller RCP para poblaci\u00f3n extranjera"},{"@type":"BreadcrumbList","@id":"https:\/\/riberasalud.com\/rsc\/2026\/03\/10\/el-hospital-del-vinalopo-impulsa-taller-de-rcp-y-primeros-auxilios-para-la-comunidad-extranjera-de-hondon-de-las-nieves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/riberasalud.com\/rsc\/"},{"@type":"ListItem","position":2,"name":"El Hospital del Vinalop\u00f3 impulsa taller de RCP y primeros auxilios para la comunidad extranjera de Hond\u00f3n de las Nieves"}]},{"@type":"WebSite","@id":"https:\/\/riberasalud.com\/rsc\/#website","url":"https:\/\/riberasalud.com\/rsc\/","name":"RSC Grupo sanitario Ribera","description":"","publisher":{"@id":"https:\/\/riberasalud.com\/rsc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/riberasalud.com\/rsc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/riberasalud.com\/rsc\/#organization","name":"RSC Grupo sanitario Ribera","url":"https:\/\/riberasalud.com\/rsc\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/riberasalud.com\/rsc\/#\/schema\/logo\/image\/","url":"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2021\/05\/cropped-Logotipo-Red.png","contentUrl":"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2021\/05\/cropped-Logotipo-Red.png","width":500,"height":198,"caption":"RSC Grupo sanitario Ribera"},"image":{"@id":"https:\/\/riberasalud.com\/rsc\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/riberasalud.com\/rsc\/#\/schema\/person\/11c4e77d56d084661ced188afcae969f","name":"Mar Sanchez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/riberasalud.com\/rsc\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5fc005413aafe0a1f7d81747fac73740246ee36e4fad7f56eb325711b6c9f209?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5fc005413aafe0a1f7d81747fac73740246ee36e4fad7f56eb325711b6c9f209?s=96&d=mm&r=g","caption":"Mar Sanchez"},"url":"https:\/\/riberasalud.com\/rsc\/author\/msotoriberasalud-es\/"}]}},"author_meta":{"display_name":"Mar Sanchez","author_link":"https:\/\/riberasalud.com\/rsc\/author\/msotoriberasalud-es\/"},"featured_img":"https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2-300x200.jpeg","pbg_featured_image_src":{"full":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"thumbnail":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2-150x150.jpeg",150,150,true],"medium":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2-300x200.jpeg",300,200,true],"medium_large":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2-768x512.jpeg",768,512,true],"large":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xxl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xxxl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xxxxl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xxxxxl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"1536x1536":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"2048x2048":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false]},"pbg_author_info":{"display_name":"Mar Sanchez","author_link":"https:\/\/riberasalud.com\/rsc\/author\/msotoriberasalud-es\/","author_img":"<img alt='Mar Sanchez' src='https:\/\/secure.gravatar.com\/avatar\/5fc005413aafe0a1f7d81747fac73740246ee36e4fad7f56eb325711b6c9f209?s=128&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/5fc005413aafe0a1f7d81747fac73740246ee36e4fad7f56eb325711b6c9f209?s=256&#038;d=mm&#038;r=g 2x' class='avatar avatar-128 photo' height='128' width='128' loading='lazy' decoding='async'\/>"},"pbg_comment_info":" No Comments","pbg_excerpt":"El Departamento de Salud del Vinalop\u00f3, del grupo sanitario Ribera, en colaboraci\u00f3n con el Ayuntamiento de Hond\u00f3n de las Nieves, ha organizado un taller de Reanimaci\u00f3n Cardiopulmonar (RCP) y primeros auxilios dirigido a la poblaci\u00f3n extranjera del municipio. El taller ha sido impartido \u00edntegramente en ingl\u00e9s por Juan Miguel Alarc\u00f3n y Marien Beras, m\u00e9dicos residentes&hellip;","uagb_featured_image_src":{"full":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"thumbnail":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2-150x150.jpeg",150,150,true],"medium":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2-300x200.jpeg",300,200,true],"medium_large":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2-768x512.jpeg",768,512,true],"large":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xxl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xxxl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xxxxl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"xxxxxl":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"1536x1536":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false],"2048x2048":["https:\/\/riberasalud.com\/rsc\/wp-content\/uploads\/2026\/03\/NP-RCP-poblacion-extranjera-2.jpeg",800,533,false]},"uagb_author_info":{"display_name":"Mar Sanchez","author_link":"https:\/\/riberasalud.com\/rsc\/author\/msotoriberasalud-es\/"},"uagb_comment_info":0,"uagb_excerpt":"El Departamento de Salud del Vinalop\u00f3, del grupo sanitario Ribera, en colaboraci\u00f3n con el Ayuntamiento de Hond\u00f3n de las Nieves, ha organizado un taller de Reanimaci\u00f3n Cardiopulmonar (RCP) y primeros auxilios dirigido a la poblaci\u00f3n extranjera del municipio. El taller ha sido impartido \u00edntegramente en ingl\u00e9s por Juan Miguel Alarc\u00f3n y Marien Beras, m\u00e9dicos residentes&hellip;","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/riberasalud.com\/rsc\/category\/alianzas-con-el-entorno\/\" class=\"advgb-post-tax-term\">Alianzas con el entorno<\/a>","<a href=\"https:\/\/riberasalud.com\/rsc\/category\/educacion-para-la-salud\/\" class=\"advgb-post-tax-term\">Educaci\u00f3n para la salud<\/a>","<a href=\"https:\/\/riberasalud.com\/rsc\/category\/promocion-de-la-salud\/\" class=\"advgb-post-tax-term\">Promoci\u00f3n de la salud<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Alianzas con el entorno<\/span>","<span class=\"advgb-post-tax-term\">Educaci\u00f3n para la salud<\/span>","<span class=\"advgb-post-tax-term\">Promoci\u00f3n de la salud<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/riberasalud.com\/rsc\/category\/promocion-de-la-salud\/\" class=\"advgb-post-tax-term\">extranjeros<\/a>","<a href=\"https:\/\/riberasalud.com\/rsc\/category\/promocion-de-la-salud\/\" class=\"advgb-post-tax-term\">primeros auxilios<\/a>","<a href=\"https:\/\/riberasalud.com\/rsc\/category\/promocion-de-la-salud\/\" class=\"advgb-post-tax-term\">rcp<\/a>","<a href=\"https:\/\/riberasalud.com\/rsc\/category\/promocion-de-la-salud\/\" class=\"advgb-post-tax-term\">taller<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">extranjeros<\/span>","<span class=\"advgb-post-tax-term\">primeros auxilios<\/span>","<span class=\"advgb-post-tax-term\">rcp<\/span>","<span class=\"advgb-post-tax-term\">taller<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 2 meses hace","modified":"Actualizado 2 meses hace"},"absolute_dates":{"created":"Publicado el 10 de marzo de 2026","modified":"Actualizado el 10 de marzo de 2026"},"absolute_dates_time":{"created":"Publicado el 10 de marzo de 2026 12:32","modified":"Actualizado el 10 de marzo de 2026 12:32"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/riberasalud.com\/rsc\/wp-json\/wp\/v2\/posts\/4792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riberasalud.com\/rsc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/riberasalud.com\/rsc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/riberasalud.com\/rsc\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/riberasalud.com\/rsc\/wp-json\/wp\/v2\/comments?post=4792"}],"version-history":[{"count":1,"href":"https:\/\/riberasalud.com\/rsc\/wp-json\/wp\/v2\/posts\/4792\/revisions"}],"predecessor-version":[{"id":4794,"href":"https:\/\/riberasalud.com\/rsc\/wp-json\/wp\/v2\/posts\/4792\/revisions\/4794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riberasalud.com\/rsc\/wp-json\/wp\/v2\/media\/4793"}],"wp:attachment":[{"href":"https:\/\/riberasalud.com\/rsc\/wp-json\/wp\/v2\/media?parent=4792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/riberasalud.com\/rsc\/wp-json\/wp\/v2\/categories?post=4792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/riberasalud.com\/rsc\/wp-json\/wp\/v2\/tags?post=4792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}