{"id":69,"count":1,"description":"","link":"https:\/\/riberasalud.com\/clinica-pasarela\/category\/neumologia\/","name":"Neumolog\u00eda","slug":"neumologia","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neumolog\u00eda archivos - Cl\u00ednica Pasarela<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/riberasalud.com\/clinica-pasarela\/category\/neumologia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neumolog\u00eda archivos - Cl\u00ednica Pasarela\" \/>\n<meta property=\"og:url\" content=\"https:\/\/riberasalud.com\/clinica-pasarela\/category\/neumologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Cl\u00ednica Pasarela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/category\\\/neumologia\\\/\",\"url\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/category\\\/neumologia\\\/\",\"name\":\"Neumolog\u00eda archivos - Cl\u00ednica Pasarela\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/category\\\/neumologia\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/category\\\/neumologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neumolog\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/#website\",\"url\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/\",\"name\":\"Cl\u00ednica Pasarela\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/#organization\",\"name\":\"Cl\u00ednica Pasarela\",\"url\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Clinica-Ribera-Pasarela-Logotipo.png\",\"contentUrl\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-Clinica-Ribera-Pasarela-Logotipo.png\",\"width\":351,\"height\":70,\"caption\":\"Cl\u00ednica Pasarela\"},\"image\":{\"@id\":\"https:\\\/\\\/riberasalud.com\\\/clinica-pasarela\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neumolog\u00eda archivos - Cl\u00ednica Pasarela","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/riberasalud.com\/clinica-pasarela\/category\/neumologia\/","og_locale":"es_ES","og_type":"article","og_title":"Neumolog\u00eda archivos - Cl\u00ednica Pasarela","og_url":"https:\/\/riberasalud.com\/clinica-pasarela\/category\/neumologia\/","og_site_name":"Cl\u00ednica Pasarela","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/riberasalud.com\/clinica-pasarela\/category\/neumologia\/","url":"https:\/\/riberasalud.com\/clinica-pasarela\/category\/neumologia\/","name":"Neumolog\u00eda archivos - Cl\u00ednica Pasarela","isPartOf":{"@id":"https:\/\/riberasalud.com\/clinica-pasarela\/#website"},"breadcrumb":{"@id":"https:\/\/riberasalud.com\/clinica-pasarela\/category\/neumologia\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/riberasalud.com\/clinica-pasarela\/category\/neumologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/riberasalud.com\/clinica-pasarela\/"},{"@type":"ListItem","position":2,"name":"Neumolog\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/riberasalud.com\/clinica-pasarela\/#website","url":"https:\/\/riberasalud.com\/clinica-pasarela\/","name":"Cl\u00ednica Pasarela","description":"","publisher":{"@id":"https:\/\/riberasalud.com\/clinica-pasarela\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/riberasalud.com\/clinica-pasarela\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/riberasalud.com\/clinica-pasarela\/#organization","name":"Cl\u00ednica Pasarela","url":"https:\/\/riberasalud.com\/clinica-pasarela\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/riberasalud.com\/clinica-pasarela\/#\/schema\/logo\/image\/","url":"https:\/\/riberasalud.com\/clinica-pasarela\/wp-content\/uploads\/2025\/05\/cropped-Clinica-Ribera-Pasarela-Logotipo.png","contentUrl":"https:\/\/riberasalud.com\/clinica-pasarela\/wp-content\/uploads\/2025\/05\/cropped-Clinica-Ribera-Pasarela-Logotipo.png","width":351,"height":70,"caption":"Cl\u00ednica Pasarela"},"image":{"@id":"https:\/\/riberasalud.com\/clinica-pasarela\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/riberasalud.com\/clinica-pasarela\/wp-json\/wp\/v2\/categories\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riberasalud.com\/clinica-pasarela\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/riberasalud.com\/clinica-pasarela\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/riberasalud.com\/clinica-pasarela\/wp-json\/wp\/v2\/posts?categories=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}