{"id":1746,"count":1,"description":"","link":"https:\/\/riberasalud.com\/blog-de-salud\/tag\/bebidas-energeticas\/","name":"Bebidas energ\u00e9ticas","slug":"bebidas-energeticas","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bebidas energ\u00e9ticas archivos - Blog de Salud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/riberasalud.com\/blog-de-salud\/tag\/bebidas-energeticas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bebidas energ\u00e9ticas archivos - Blog de Salud\" \/>\n<meta property=\"og:url\" content=\"https:\/\/riberasalud.com\/blog-de-salud\/tag\/bebidas-energeticas\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Salud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/tag\\\/bebidas-energeticas\\\/\",\"url\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/tag\\\/bebidas-energeticas\\\/\",\"name\":\"Bebidas energ\u00e9ticas archivos - Blog de Salud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/tag\\\/bebidas-energeticas\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/tag\\\/bebidas-energeticas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bebidas energ\u00e9ticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/#website\",\"url\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/\",\"name\":\"Blog de Salud\",\"description\":\"Grupo Ribera\",\"publisher\":{\"@id\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/#organization\",\"name\":\"Blog de Salud\",\"url\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-Logotipo-Red-qgbhgk.png\",\"contentUrl\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-Logotipo-Red-qgbhgk.png\",\"width\":5001,\"height\":1976,\"caption\":\"Blog de Salud\"},\"image\":{\"@id\":\"https:\\\/\\\/riberasalud.com\\\/blog-de-salud\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bebidas energ\u00e9ticas archivos - Blog de Salud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/riberasalud.com\/blog-de-salud\/tag\/bebidas-energeticas\/","og_locale":"es_ES","og_type":"article","og_title":"Bebidas energ\u00e9ticas archivos - Blog de Salud","og_url":"https:\/\/riberasalud.com\/blog-de-salud\/tag\/bebidas-energeticas\/","og_site_name":"Blog de Salud","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/riberasalud.com\/blog-de-salud\/tag\/bebidas-energeticas\/","url":"https:\/\/riberasalud.com\/blog-de-salud\/tag\/bebidas-energeticas\/","name":"Bebidas energ\u00e9ticas archivos - Blog de Salud","isPartOf":{"@id":"https:\/\/riberasalud.com\/blog-de-salud\/#website"},"breadcrumb":{"@id":"https:\/\/riberasalud.com\/blog-de-salud\/tag\/bebidas-energeticas\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/riberasalud.com\/blog-de-salud\/tag\/bebidas-energeticas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/riberasalud.com\/blog-de-salud\/"},{"@type":"ListItem","position":2,"name":"Bebidas energ\u00e9ticas"}]},{"@type":"WebSite","@id":"https:\/\/riberasalud.com\/blog-de-salud\/#website","url":"https:\/\/riberasalud.com\/blog-de-salud\/","name":"Blog de Salud","description":"Grupo Ribera","publisher":{"@id":"https:\/\/riberasalud.com\/blog-de-salud\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/riberasalud.com\/blog-de-salud\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/riberasalud.com\/blog-de-salud\/#organization","name":"Blog de Salud","url":"https:\/\/riberasalud.com\/blog-de-salud\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/riberasalud.com\/blog-de-salud\/#\/schema\/logo\/image\/","url":"https:\/\/riberasalud.com\/blog-de-salud\/wp-content\/uploads\/2022\/09\/cropped-Logotipo-Red-qgbhgk.png","contentUrl":"https:\/\/riberasalud.com\/blog-de-salud\/wp-content\/uploads\/2022\/09\/cropped-Logotipo-Red-qgbhgk.png","width":5001,"height":1976,"caption":"Blog de Salud"},"image":{"@id":"https:\/\/riberasalud.com\/blog-de-salud\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/riberasalud.com\/blog-de-salud\/wp-json\/wp\/v2\/tags\/1746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riberasalud.com\/blog-de-salud\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/riberasalud.com\/blog-de-salud\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/riberasalud.com\/blog-de-salud\/wp-json\/wp\/v2\/posts?tags=1746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}